{"id":869,"date":"2025-09-25T00:14:51","date_gmt":"2025-09-25T00:14:51","guid":{"rendered":"http:\/\/www.mutuelle-mat.fr\/blog\/quel-document-pour-resilier-assurance-habitation\/869.html"},"modified":"2025-09-25T00:14:51","modified_gmt":"2025-09-25T00:14:51","slug":"quel-document-pour-resilier-assurance-habitation","status":"publish","type":"post","link":"http:\/\/www.mutuelle-mat.fr\/blog\/quel-document-pour-resilier-assurance-habitation\/869.html","title":{"rendered":"Quel document pour r\u00e9silier assurance habitation ?"},"content":{"rendered":"<p>                                        <img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/SMVRW6jEcM4\/hq720.jpg?sqp=-oaymwEcCOgCEMoBSFXyq4qpAw4IARUAAIhCGAFwAcABBg==&#038;rs=AOn4CLARWq8ZgLGtPVy1qd-b1de1M54QVg\" alt=\"Quel document pour r\u00e9silier assurance habitation ?\"><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaires<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97d2c18242b\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97d2c18242b\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/quel-document-pour-resilier-assurance-habitation\/869.html\/#Quel_document_pour_resilier_assurance_habitation\" >Quel document pour r\u00e9silier assurance habitation ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/quel-document-pour-resilier-assurance-habitation\/869.html\/#Quel_est_le_delai_de_resiliation_dune_assurance_habitation\" >Quel est le d\u00e9lai de r\u00e9siliation d&#39;une assurance habitation?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/quel-document-pour-resilier-assurance-habitation\/869.html\/#Comment_resilier_mon_contrat_dassurance\" >Comment r\u00e9silier mon contrat d\u2019assurance?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/quel-document-pour-resilier-assurance-habitation\/869.html\/#Quelle_lettre_de_resiliation_de_contrat_dassurance_doit_etre_envoyee_en_recommande\" >Quelle lettre de r\u00e9siliation de contrat d&#39;assurance doit \u00eatre envoy\u00e9e en recommand\u00e9?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/quel-document-pour-resilier-assurance-habitation\/869.html\/#Quelle_est_la_procedure_de_resiliation_de_votre_logement\" >Quelle est la proc\u00e9dure de r\u00e9siliation de votre logement?<\/a><\/li><\/ul><\/nav><\/div>\n<h3 id=\"question-0\"><span class=\"ez-toc-section\" id=\"Quel_document_pour_resilier_assurance_habitation\"><\/span>Quel document pour r\u00e9silier assurance habitation ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Joignez \u00e0 votre demande un justificatif : une copie de votre nouveau contrat de bail ou une quittance de loyer, ou une facture d&rsquo;\u00e9lectricit\u00e9, de gaz ou de t\u00e9l\u00e9phone pour votre nouveau logement. Il est aussi possible d&rsquo;envoyer une copie de l&rsquo;\u00e9tat de lieux de sortie de votre pr\u00e9c\u00e9dente habitation.<\/p>\n<h3 id=\"question-1\"><span class=\"ez-toc-section\" id=\"Quel_est_le_delai_de_resiliation_dune_assurance_habitation\"><\/span>Quel est le d\u00e9lai de r\u00e9siliation d&#39;une assurance habitation?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Quel est le d\u00e9lai de r\u00e9siliation d\u2019une assurance habitation apr\u00e8s une vente de logement ? Le d\u00e9lai de r\u00e9siliation est d\u2019un mois maximum apr\u00e8s la r\u00e9ception de votre demande de cl\u00f4ture de contrat. Vous serez ensuite rembours\u00e9 de la somme correspondant \u00e0 la partie de prime d&rsquo;assurance habitation d\u00e9j\u00e0 vers\u00e9e et non couverte. <\/li>\n<\/ul>\n<h3 id=\"question-2\"><span class=\"ez-toc-section\" id=\"Comment_resilier_mon_contrat_dassurance\"><\/span>Comment r\u00e9silier mon contrat d\u2019assurance?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception. Objet : R\u00e9siliation de mon contrat d\u2019assurance. (Madame, Monsieur), Je vous adresse ce pr\u00e9sent courrier pour vous informer de ma d\u00e9cision de mettre fin \u00e0 mon contrat d\u2019assurance n\u00b0 XXXX (indiquer le num\u00e9ro du contrat d\u2019assurance concern\u00e9 par la r\u00e9siliation) portant sur &#8230; <\/li>\n<\/ul>\n<h3 id=\"question-3\"><span class=\"ez-toc-section\" id=\"Quelle_lettre_de_resiliation_de_contrat_dassurance_doit_etre_envoyee_en_recommande\"><\/span>Quelle lettre de r\u00e9siliation de contrat d&#39;assurance doit \u00eatre envoy\u00e9e en recommand\u00e9?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Votre lettre de r\u00e9siliation de contrat d&rsquo;assurance doit \u00eatre envoy\u00e9e en recommand\u00e9 avec demande d&rsquo;avis de r\u00e9ception. <\/li>\n<\/ul>\n<h3 id=\"question-4\"><span class=\"ez-toc-section\" id=\"Quelle_est_la_procedure_de_resiliation_de_votre_logement\"><\/span>Quelle est la proc\u00e9dure de r\u00e9siliation de votre logement?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>La seule condition est de joindre un justificatif de cette cession (copie de l\u2019acte de vente) \u00e0 votre courrier de r\u00e9siliation. La proc\u00e9dure reste la m\u00eame que vous vous chargiez vous-m\u00eame de vendre votre logement, ou que vous passiez par un agent immobilier, avec mandat simple ou exclusif. 2. <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Quel document pour r\u00e9silier assurance habitation ? Joignez \u00e0 votre demande un justificatif : une copie de votre nouveau contrat de bail ou une quittance de loyer, ou une facture d&rsquo;\u00e9lectricit\u00e9, de gaz ou de t\u00e9l\u00e9phone pour votre nouveau logement. Il est aussi possible d&rsquo;envoyer une copie de l&rsquo;\u00e9tat de<\/p>\n","protected":false},"author":1,"featured_media":388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prevoyance"],"_links":{"self":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":0,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts\/869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/media\/388"}],"wp:attachment":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/media?parent=869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/categories?post=869"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/tags?post=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}