{"id":839,"date":"2025-09-22T07:01:45","date_gmt":"2025-09-22T07:01:45","guid":{"rendered":"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html"},"modified":"2025-09-22T07:01:45","modified_gmt":"2025-09-22T07:01:45","slug":"comment-fonctionne-la-succession-dune-assurance-vie","status":"publish","type":"post","link":"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html","title":{"rendered":"Comment fonctionne la succession d&rsquo;une assurance vie ?"},"content":{"rendered":"<p>                                        <img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/R731D-nbahk\/hq720.jpg?sqp=-oaymwEcCOgCEMoBSFXyq4qpAw4IARUAAIhCGAFwAcABBg==&#038;rs=AOn4CLBm_H2loJRsxi0VskNYgULN24Y7Uw\" alt=\"Comment fonctionne la succession d'une assurance vie ?\"><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaires<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97f03563558\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97f03563558\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Comment_fonctionne_la_succession_dune_assurance_vie\" >Comment fonctionne la succession d&rsquo;une assurance vie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Quest-ce_quun_compte_GMO\" >Qu&rsquo;est-ce qu&rsquo;un compte GMO ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Pourquoi_les_montants_des_capitaux_des_contrats_dAssurance-vie_ne_figurent_pas_dans_la_succession\" >Pourquoi les montants des capitaux des contrats d&rsquo;Assurance-vie ne figurent pas dans la succession ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Quest-ce_que_GMO_Poste_Avenir\" >Qu&rsquo;est-ce que GMO Poste Avenir ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Comment_fonctionne_un_GMO\" >Comment fonctionne un GMO ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Quelles_conditions_doit_respecter_un_beneficiaire_pour_toucher_le_capital_deces_avec_les_avantages_fiscaux_de_lassurance_vie\" >Quelles conditions doit respecter un b\u00e9n\u00e9ficiaire pour toucher le capital d\u00e9c\u00e8s avec les avantages fiscaux de l&rsquo;assurance vie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Est-ce_que_lassurance_vie_securise_la_succession\" >Est-ce que l\u2019assurance vie s\u00e9curise la succession?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Quelle_est_la_fiscalite_applicable_a_la_succession_dassurance-vie\" >Quelle est la fiscalit\u00e9 applicable \u00e0 la succession d\u2019assurance-vie?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Comment_sont_imposables_les_droits_de_succession\" >Comment sont imposables les droits de succession?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-fonctionne-la-succession-dune-assurance-vie\/839.html\/#Quelle_est_lassurance_vie\" >Quelle est l&#39;assurance vie?<\/a><\/li><\/ul><\/nav><\/div>\n<h3 id=\"question-0\"><span class=\"ez-toc-section\" id=\"Comment_fonctionne_la_succession_dune_assurance_vie\"><\/span>Comment fonctionne la succession d&rsquo;une assurance vie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>L&rsquo;assurance vie est-elle soumise au droit de succession ? Non, l&rsquo;assurance vie n&rsquo;est pas soumise au droit de succession. Elle b\u00e9n\u00e9ficie d&rsquo;une fiscalit\u00e9 plus avantageuse qui d\u00e9pend de plusieurs facteurs : la date de souscription du contrat, la date des versements et l&rsquo;\u00e2ge de l&rsquo;assur\u00e9 lors des versements.<\/p>\n<h3 id=\"question-1\"><span class=\"ez-toc-section\" id=\"Quest-ce_quun_compte_GMO\"><\/span>Qu&rsquo;est-ce qu&rsquo;un compte GMO ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>GMO est un contrat MultiSupports d&rsquo;assurance-vie qui vous permet de pr\u00e9parer, \u00e0 votre rythme une \u00e9pargne. L&rsquo;assurance vie GMO est un contrat de type Collectif, c&rsquo;est \u00e0 dire que l&rsquo;assur\u00e9 est donc repr\u00e9sent\u00e9 aupr\u00e8s de l&rsquo;assureur CNP ASSURANCES par une association d&rsquo;assur\u00e9.<\/p>\n<\/p>\n<h3 id=\"question-2\"><span class=\"ez-toc-section\" id=\"Pourquoi_les_montants_des_capitaux_des_contrats_dAssurance-vie_ne_figurent_pas_dans_la_succession\"><\/span>Pourquoi les montants des capitaux des contrats d&rsquo;Assurance-vie ne figurent pas dans la succession ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>A. L&rsquo;article L132-12 du Code des Assurances dispose : \u00ab Le capital ou la rente stipul\u00e9s payables lors du d\u00e9c\u00e8s de l&rsquo;assur\u00e9 \u00e0 un b\u00e9n\u00e9ficiaire d\u00e9termin\u00e9 ou \u00e0 ses h\u00e9ritiers ne font pas partie de la succession de l&rsquo;assur\u00e9. &#8230; En effet, il est possible que le b\u00e9n\u00e9ficiaire ignore \u00eatre b\u00e9n\u00e9ficiaire d&rsquo;un contrat d&rsquo;assurance-vie.<\/p>\n<h3 id=\"question-3\"><span class=\"ez-toc-section\" id=\"Quest-ce_que_GMO_Poste_Avenir\"><\/span>Qu&rsquo;est-ce que GMO Poste Avenir ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le contrat GMO Poste Avenir est un contrat d&rsquo;assurance-vie multisupport distribu\u00e9 par La Banque Postale et assur\u00e9 par CNP Assurances . &#8230;<\/p>\n<h3 id=\"question-4\"><span class=\"ez-toc-section\" id=\"Comment_fonctionne_un_GMO\"><\/span>Comment fonctionne un GMO ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>GMO est une assurance-vie multisupport \u2013 diversifi\u00e9e en actions risqu\u00e9es et obligations plus s\u00fbres. C&rsquo; est un fonds en euros, dont les capitaux sont majoritairement investis en obligations plus s\u00e9curis\u00e9es avec un zeste d&rsquo; actions risqu\u00e9es. Les produits d&rsquo; assurance-vie sont des placements financiers.<\/p>\n<\/p>\n<h3 id=\"question-5\"><span class=\"ez-toc-section\" id=\"Quelles_conditions_doit_respecter_un_beneficiaire_pour_toucher_le_capital_deces_avec_les_avantages_fiscaux_de_lassurance_vie\"><\/span>Quelles conditions doit respecter un b\u00e9n\u00e9ficiaire pour toucher le capital d\u00e9c\u00e8s avec les avantages fiscaux de l&rsquo;assurance vie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Capital d\u00e9c\u00e8s : quelles formalit\u00e9s pour le percevoir ? Pour qu&rsquo;il y ait transmission de l&rsquo;assurance vie, le b\u00e9n\u00e9ficiaire doit attester du d\u00e9c\u00e8s du souscripteur aupr\u00e8s de l&rsquo;assureur en lui transmettant une copie de l&rsquo;acte de d\u00e9c\u00e8s. Pour percevoir le capital d\u00e9c\u00e8s, le b\u00e9n\u00e9ficiaire doit prouver sa qualit\u00e9.<\/p>\n<h3 id=\"question-6\"><span class=\"ez-toc-section\" id=\"Est-ce_que_lassurance_vie_securise_la_succession\"><\/span>Est-ce que l\u2019assurance vie s\u00e9curise la succession?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Faisant int\u00e9gralement partie de la succession, ce type de contrat s\u00e9curise la souscription. Surtout que fiscalement l\u2019avantage comparatif de l\u2019assurance vie se r\u00e9duit apr\u00e8s 70 ans, les primes vers\u00e9es \u00e9tant soumises au bar\u00e8me des droits de succession apr\u00e8s un abattement commun aux b\u00e9n\u00e9ficiaires de 30.500 euros (article 757 B du CGI). <\/li>\n<\/ul>\n<h3 id=\"question-7\"><span class=\"ez-toc-section\" id=\"Quelle_est_la_fiscalite_applicable_a_la_succession_dassurance-vie\"><\/span>Quelle est la fiscalit\u00e9 applicable \u00e0 la succession d\u2019assurance-vie?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>La fiscalit\u00e9 applicable \u00e0 la succession de l\u2019assurance-vie d\u00e9pend de l\u2019\u00e2ge de l\u2019assur\u00e9 au moment des versements. Deux situations se distinguent : les versements effectu\u00e9s avant 70 ans et ceux effectu\u00e9s apr\u00e8s 70 ans. <\/li>\n<\/ul>\n<h3 id=\"question-8\"><span class=\"ez-toc-section\" id=\"Comment_sont_imposables_les_droits_de_succession\"><\/span>Comment sont imposables les droits de succession?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>aux droits de succession : sont imposables aux droits de succession les primes vers\u00e9es apr\u00e8s 70 ans et sup\u00e9rieures \u00e0 30 500 \u20ac (contrats souscrits apr\u00e8s le 20 novembre 1991). Pour appr\u00e9cier ce seuil de 30 500 \u20ac, l&rsquo;ensemble des contrats souscrits sur la t\u00eate d&rsquo;un m\u00eame assur\u00e9 doivent \u00eatre pris en compte. <\/li>\n<\/ul>\n<h3 id=\"question-9\"><span class=\"ez-toc-section\" id=\"Quelle_est_lassurance_vie\"><\/span>Quelle est l&#39;assurance vie?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>L&rsquo;assurance vie permet d&rsquo;optimiser la transmission de son patrimoine, en respectant les r\u00e8gles du droit des successions. Le Code civil pr\u00e9voit que les enfants ont droit \u00e0 une part de la succession qui leur est garantie (de m\u00eame pour le conjoint, \u00e0 d\u00e9faut de descendant). Cette part est appel\u00e9e \u00abr\u00e9serve h\u00e9r\u00e9ditaire\u00bb. <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Comment fonctionne la succession d&rsquo;une assurance vie ? L&rsquo;assurance vie est-elle soumise au droit de succession ? Non, l&rsquo;assurance vie n&rsquo;est pas soumise au droit de succession. Elle b\u00e9n\u00e9ficie d&rsquo;une fiscalit\u00e9 plus avantageuse qui d\u00e9pend de plusieurs facteurs : la date de souscription du contrat, la date des versements et<\/p>\n","protected":false},"author":1,"featured_media":491,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prevoyance"],"_links":{"self":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/comments?post=839"}],"version-history":[{"count":0,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts\/839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/media\/491"}],"wp:attachment":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/categories?post=839"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}