{"id":576,"date":"2022-10-20T14:00:32","date_gmt":"2022-10-20T14:00:32","guid":{"rendered":"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html"},"modified":"2022-10-20T14:00:32","modified_gmt":"2022-10-20T14:00:32","slug":"comment-rediger-la-clause-beneficiaire-dune-assurance-vie","status":"publish","type":"post","link":"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html","title":{"rendered":"Comment r\u00e9diger la clause b\u00e9n\u00e9ficiaire d&rsquo;une assurance vie ?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/bvm5lesvXio\/hq720.jpg?sqp=-oaymwEcCOgCEMoBSFXyq4qpAw4IARUAAIhCGAFwAcABBg==&#038;rs=AOn4CLCFYdZrUW67-DEKgg5H5VN1-aHSeg\" alt=\"Comment r\u00e9diger la clause b\u00e9n\u00e9ficiaire d'une assurance vie ?\"><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaires<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a989ae1c94cb\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a989ae1c94cb\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Comment_rediger_la_clause_beneficiaire_dune_assurance_vie\" >Comment r\u00e9diger la clause b\u00e9n\u00e9ficiaire d&rsquo;une assurance vie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Comment_enlever_un_beneficiaire_dune_assurance_vie\" >Comment enlever un b\u00e9n\u00e9ficiaire d&rsquo;une assurance vie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Quelle_est_la_clause_beneficiaire_standard_dun_contrat_dassurance_vie\" >Quelle est la clause b\u00e9n\u00e9ficiaire standard d&rsquo;un contrat d&rsquo;assurance vie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Comment_changer_de_nom_sur_une_assurance_vie\" >Comment changer de nom sur une assurance vie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Qui_mettre_comme_beneficiaire_assurance_vie\" >Qui mettre comme b\u00e9n\u00e9ficiaire assurance vie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Comment_contester_un_contrat_dassurance\" >Comment contester un contrat d&rsquo;assurance ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Quelle_est_la_clause_beneficiaire_de_lassurance-vie\" >Quelle est la clause b\u00e9n\u00e9ficiaire de l&#39;assurance-vie?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Quelle_est_la_clause_standard_dassurance_vie\" >Quelle est la clause standard d\u2019assurance vie?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Comment_beneficier_de_la_fiscalite_de_lassurance_vie\" >Comment b\u00e9n\u00e9ficier de la fiscalit\u00e9 de l\u2019assurance vie?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"http:\/\/www.mutuelle-mat.fr\/blog\/comment-rediger-la-clause-beneficiaire-dune-assurance-vie\/576.html\/#Comment_designer_un_beneficiaire_dassurance_vie\" >Comment d\u00e9signer un b\u00e9n\u00e9ficiaire d&#39;assurance vie?<\/a><\/li><\/ul><\/nav><\/div>\n<h3 id=\"question-0\"><span class=\"ez-toc-section\" id=\"Comment_rediger_la_clause_beneficiaire_dune_assurance_vie\"><\/span>Comment r\u00e9diger la clause b\u00e9n\u00e9ficiaire d&rsquo;une assurance vie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Assurance vie : comment bien r\u00e9diger la clause b\u00e9n\u00e9ficiaire ?<\/p>\n<li>Assurez-vous de d\u00e9signer au moins un b\u00e9n\u00e9ficiaire. &#8230; <\/li>\n<li>Pr\u00e9voyez des b\u00e9n\u00e9ficiaires en cascade. &#8230; <\/li>\n<li>D\u00e9signez le conjoint par sa qualit\u00e9 &#8230; <\/li>\n<li>La repr\u00e9sentation ne se pr\u00e9sume pas. &#8230; <\/li>\n<li>N&rsquo;utilisez que des pourcentages pour r\u00e9partir le capital.<\/li>\n<h3 id=\"question-1\"><span class=\"ez-toc-section\" id=\"Comment_enlever_un_beneficiaire_dune_assurance_vie\"><\/span>Comment enlever un b\u00e9n\u00e9ficiaire d&rsquo;une assurance vie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Pour modifier le b\u00e9n\u00e9ficiaire, il y a deux cas de figure : Soit le b\u00e9n\u00e9ficiaire n&rsquo;\u00e9tait pas formellement inform\u00e9 et dans ce cas, le souscripteur peut informer son assureur du changement par lettre simple. Ceci donnera lieu \u00e0 un avenant au contrat qui modifiera la clause b\u00e9n\u00e9ficiaire.<\/p>\n<\/p>\n<h3 id=\"question-2\"><span class=\"ez-toc-section\" id=\"Quelle_est_la_clause_beneficiaire_standard_dun_contrat_dassurance_vie\"><\/span>Quelle est la clause b\u00e9n\u00e9ficiaire standard d&rsquo;un contrat d&rsquo;assurance vie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La clause b\u00e9n\u00e9ficiaire de votre assurance vie sert \u00e0 d\u00e9signer la ou les personne(s) qui percevront le capital lorsque surviendra votre d\u00e9c\u00e8s. Ainsi, lors du d\u00e9c\u00e8s du souscripteur, le capital est vers\u00e9 aux b\u00e9n\u00e9ficiaires d\u00e9sign\u00e9s dans le contrat, selon la r\u00e9partition choisie.<\/p>\n<h3 id=\"question-3\"><span class=\"ez-toc-section\" id=\"Comment_changer_de_nom_sur_une_assurance_vie\"><\/span>Comment changer de nom sur une assurance vie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Modifier la clause b\u00e9n\u00e9ficiaire d&rsquo;une assurance vie Le d\u00e9tenteur de l&rsquo;assurance vie peut alors modifier \u00e0 tout moment le nom du ou des b\u00e9n\u00e9ficiaires, en envoyant une simple lettre \u00e0 son assureur vie. La clause b\u00e9n\u00e9ficiaire est alors modifi\u00e9e par un avenant au contrat.<\/p>\n<h3 id=\"question-4\"><span class=\"ez-toc-section\" id=\"Qui_mettre_comme_beneficiaire_assurance_vie\"><\/span>Qui mettre comme b\u00e9n\u00e9ficiaire assurance vie ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Qui peut \u00eatre un b\u00e9n\u00e9ficiaire? Vous pouvez d\u00e9signer votre conjoint, vos enfants, vos personnes \u00e0 charge, un autre membre de la famille, un ami ou une \u0153uvre de charit\u00e9 \u00e0 titre de b\u00e9n\u00e9ficiaire. Si vous d\u00e9signez plusieurs b\u00e9n\u00e9ficiaires, la compagnie d&rsquo;assurance divisera la prestation de d\u00e9c\u00e8s entre eux.<\/p>\n<\/p>\n<h3 id=\"question-5\"><span class=\"ez-toc-section\" id=\"Comment_contester_un_contrat_dassurance\"><\/span>Comment contester un contrat d&rsquo;assurance ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Pour contester \u00e0 l&rsquo;amiable, l&rsquo;assur\u00e9 doit envoyer \u00e0 la compagnie d&rsquo;assurance une lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception mettant en avant la volont\u00e9 d&rsquo;utiliser son droit de contestation. Le courrier doit expliquer clairement les arguments avanc\u00e9s et donner des preuves (documents, photos\u2026) pour appuyer la demande.<\/p>\n<h3 id=\"question-6\"><span class=\"ez-toc-section\" id=\"Quelle_est_la_clause_beneficiaire_de_lassurance-vie\"><\/span>Quelle est la clause b\u00e9n\u00e9ficiaire de l&#39;assurance-vie?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Il est donc \u00e9vident qu&rsquo;il faut d\u00e9signer un ou plusieurs b\u00e9n\u00e9ficiaires dans votre contrat. La r\u00e9daction de la clause b\u00e9n\u00e9ficiaire de l&rsquo;assurance-vie est essentielle, car elle va strictement d\u00e9terminer la destination des sommes \u00e9pargn\u00e9es. <\/li>\n<\/ul>\n<h3 id=\"question-7\"><span class=\"ez-toc-section\" id=\"Quelle_est_la_clause_standard_dassurance_vie\"><\/span>Quelle est la clause standard d\u2019assurance vie?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>La plupart des assureurs propose une clause standard dans leur contrat d\u2019assurance vie. La r\u00e9daction de cette clause b\u00e9n\u00e9ficiaire standard permet de transmettre le patrimoine selon l\u2019ordre de succession classique : conjoint, enfants et h\u00e9ritiers. <\/li>\n<\/ul>\n<h3 id=\"question-8\"><span class=\"ez-toc-section\" id=\"Comment_beneficier_de_la_fiscalite_de_lassurance_vie\"><\/span>Comment b\u00e9n\u00e9ficier de la fiscalit\u00e9 de l\u2019assurance vie?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Afin de b\u00e9n\u00e9ficier pleinement de la fiscalit\u00e9 de l\u2019assurance vie, le contrat sur lequel seront employ\u00e9es les sommes pourra \u00eatre ouvert d\u00e8s la souscription du premier contrat. En d\u2019autres termes, un contrat est souscrit au nom du p\u00e8re ainsi qu\u2019au nom du fils mais pour une somme minime d\u00e8s la mise en place de l\u2019op\u00e9ration. <\/li>\n<\/ul>\n<h3 id=\"question-9\"><span class=\"ez-toc-section\" id=\"Comment_designer_un_beneficiaire_dassurance_vie\"><\/span>Comment d\u00e9signer un b\u00e9n\u00e9ficiaire d&#39;assurance vie?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Si vous souscrivez \u00e0 une assurance vie, vous pouvez d\u00e9signer le (s) b\u00e9n\u00e9ficiaire (s) de ce contrat d&rsquo;assurance vie. Envoyez cette lettre gratuite pour informer l&rsquo;assurance. Conform\u00e9ment \u00e0 l\u2019article L132-12 du Code des assurances, lorsque vous souscrivez une assurance-vie, la d\u00e9signation d&rsquo;un b\u00e9n\u00e9ficiaire n&rsquo;est pas obligatoire,&#8230; <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Comment r\u00e9diger la clause b\u00e9n\u00e9ficiaire d&rsquo;une assurance vie ? Assurance vie : comment bien r\u00e9diger la clause b\u00e9n\u00e9ficiaire ? Assurez-vous de d\u00e9signer au moins un b\u00e9n\u00e9ficiaire. &#8230; Pr\u00e9voyez des b\u00e9n\u00e9ficiaires en cascade. &#8230; D\u00e9signez le conjoint par sa qualit\u00e9 &#8230; La repr\u00e9sentation ne se pr\u00e9sume pas. &#8230; N&rsquo;utilisez que des<\/p>\n","protected":false},"author":1,"featured_media":577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prevoyance"],"_links":{"self":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts\/576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/comments?post=576"}],"version-history":[{"count":0,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/posts\/576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/media\/577"}],"wp:attachment":[{"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/media?parent=576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/categories?post=576"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mutuelle-mat.fr\/blog\/wp-json\/wp\/v2\/tags?post=576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}